{"id":21577,"date":"2023-02-27T00:12:29","date_gmt":"2023-02-26T23:12:29","guid":{"rendered":"https:\/\/balispirit.es\/politique-de-confidentialite\/"},"modified":"2026-03-30T09:50:46","modified_gmt":"2026-03-30T08:50:46","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/","title":{"rendered":"politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21577\" class=\"elementor elementor-21577 elementor-21559\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd30334 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd30334\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b0919a\" data-id=\"3b0919a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f6c78a elementor-widget elementor-widget-text-editor\" data-id=\"5f6c78a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t&lt;div id=&#8221;content&#8221;&gt;&lt;section class=&#8221;page-main-titles11 &#8220;&gt;&lt;div class=&#8221;container&#8221;&gt;&lt;div class=&#8221;row&#8221;&gt;&lt;div class=&#8221;col-lg-12&#8243;&gt;&lt;article id=&#8221;post-321&#8243; class=&#8221;post-321 page type-page status-publish hentry entry&#8221;&gt;&lt;div class=&#8221;entry-content&#8221;&gt;&lt;p&gt;4.- &lt;\/p&gt;&lt;p&gt;Le respect de la vie priv\u00e9e est primordial pour BALI SPIRIT, S.L. et nous souhaitons maintenir une attitude ouverte et transparente dans le traitement de vos donn\u00e9es personnelles..&lt;\/p&gt;&lt;&gt;&lt;&gt;&lt;\/p&gt;&lt;p&gt;BALI SPIRIT, S.L. est responsable du traitement des donn\u00e9es personnelles que vous nous fournissez et est responsable de ces donn\u00e9es personnelles conform\u00e9ment \u00e0 la r\u00e9glementation applicable en mati\u00e8re de protection des donn\u00e9es.&lt;br \/&gt;Nom de l&#8217;entreprise:BALI SPIRIT, S.L.&lt;br \/&gt;Num\u00e9ro d&#8217;identification fiscale : CIF B-65118481&lt;br \/&gt;Si\u00e8ge social : RueAribau, 59 08011 Barcelona&lt;br \/&gt;Num\u00e9ro de t\u00e9l\u00e9phone de contact : 934 517 085&lt;br \/&gt;Adresse \u00e9lectronique de contact :info@balispirit.es&lt;br \/&gt;  &lt;br \/&gt;O\u00f9 stockons-nous vos donn\u00e9es ?&lt;br \/&gt;Les donn\u00e9es que nous recueillons vous concernant sont stock\u00e9es au sein de l\u2019Espace \u00e9conomique europ\u00e9en (\u00ab EEE \u00bb), mais peuvent \u00e9galement \u00eatre transf\u00e9r\u00e9es et trait\u00e9es dans un pays situ\u00e9 en dehors de l\u2019EEE. Tout transfert de vos donn\u00e9es personnelles sera effectu\u00e9 conform\u00e9ment \u00e0 la l\u00e9gislation applicable. Pour les transferts hors de l\u2019EEE, GRUPO AIRE utilisera les clauses contractuelles types de protection des donn\u00e9es adopt\u00e9es par la Commission europ\u00e9enne et le Bouclier de protection des donn\u00e9es UE-\u00c9tats-Unis comme garantie pour les transferts vers des pays ne b\u00e9n\u00e9ficiant pas d\u2019une d\u00e9cision d\u2019ad\u00e9quation de la Commission europ\u00e9enne.   &lt;br \/&gt; &lt;br \/&gt;Avec qui partageons-nous vos donn\u00e9es ?&lt;br \/&gt;Vos donn\u00e9es personnelles ne seront jamais partag\u00e9es, vendues ni \u00e9chang\u00e9es avec des tiers ext\u00e9rieurs \u00e0 BALI SPIRIT, S.L. Les donn\u00e9es transmises \u00e0 des tiers seront utilis\u00e9es uniquement pour vous fournir nos services. Nous d\u00e9taillerons les cat\u00e9gories de tiers ayant acc\u00e8s \u00e0 vos donn\u00e9es pour chaque traitement sp\u00e9cifique. &lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le fondement juridique du traitement est l\u2019ex\u00e9cution du service que vous avez contract\u00e9 ainsi que le consentement que vous avez donn\u00e9 pour des finalit\u00e9s autres que ces services.&lt;br \/&gt; &lt;br \/&gt;Quels sont vos droits ?&lt;br \/&gt;Droit d&#8217;acc\u00e8s : &lt;br \/&gt;Toute personne a le droit d&#8217;obtenir la confirmation que BALI SPIRIT traite ou non des donn\u00e9es personnelles la concernant.&lt;br \/&gt; &lt;br \/&gt;Droit \u00e0 la portabilit\u00e9 :&lt;br \/&gt;Lorsque BALI SPIRIT traite vos donn\u00e9es personnelles par des moyens automatis\u00e9s, sur la base de votre consentement ou d&#8217;un contrat, vous avez le droit d&#8217;obtenir une copie de vos donn\u00e9es dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine, qui vous sera transf\u00e9r\u00e9e ou transf\u00e9r\u00e9e \u00e0 un tiers. Cette copie ne comprendra que les donn\u00e9es personnelles que vous nous avez fournies. &lt;br \/&gt; &lt;br \/&gt;Droit de rectification : &lt;br \/&gt;Vous avez le droit de demander la rectification de vos donn\u00e9es personnelles si elles sont inexactes, y compris le droit de compl\u00e9ter les donn\u00e9es qui apparaissent incompl\u00e8tes. &lt;br \/&gt; &lt;br \/&gt;Droit \u00e0 l&#8217;effacement :&lt;br \/&gt;Vous avez le droit d&#8217;obtenir \u00e0 tout moment, sans d\u00e9lai indu, l&#8217;effacement de toutes les donn\u00e9es personnelles vous concernant trait\u00e9es par BALI SPIRIT, sauf dans les situations suivantes :&lt;br \/&gt;* a un probl\u00e8me persistant avec le service client&lt;br \/&gt;* Vous avez une commande ou une r\u00e9servation en cours qui n&#8217;a pas encore \u00e9t\u00e9 honor\u00e9e, ou une commande de coffret cadeau \u00e0 livrer \u00e0 domicile qui a \u00e9t\u00e9 exp\u00e9di\u00e9e ou dont l&#8217;exp\u00e9dition n&#8217;a pas \u00e9t\u00e9 termin\u00e9e.&lt;br \/&gt;* Il est soup\u00e7onn\u00e9 ou confirm\u00e9 que vous avez fait un usage abusif de nos services au cours des quatre derni\u00e8res ann\u00e9es.&lt;br \/&gt;* Vous avez effectu\u00e9 un achat, nous conserverons donc vos donn\u00e9es personnelles relatives \u00e0 la transaction \u00e0 des fins comptables.&lt;br \/&gt;* l&#8217;existence d&#8217;une obligation l\u00e9gale de conserver vos donn\u00e9es.&lt;br \/&gt; &lt;br \/&gt;Droit de s\u2019opposer au traitement des donn\u00e9es fond\u00e9 sur l\u2019int\u00e9r\u00eat l\u00e9gitime :&lt;br \/&gt;Vous avez le droit de vous opposer au traitement de vos donn\u00e9es personnelles fond\u00e9 sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT. BALI SPIRIT cessera de traiter vos donn\u00e9es personnelles \u00e0 moins de pouvoir d\u00e9montrer l&#8217;existence de motifs l\u00e9gitimes et imp\u00e9rieux justifiant ce traitement et pr\u00e9valant sur vos int\u00e9r\u00eats, droits et libert\u00e9s, ou pour la constatation, l&#8217;exercice ou la d\u00e9fense de droits en justice. &lt;br \/&gt; &lt;br \/&gt;Droit de s&#8217;opposer au marketing direct :&lt;br \/&gt;Vous avez le droit de vous opposer au marketing direct, y compris au profilage effectu\u00e9 \u00e0 des fins de marketing direct en lien avec les services que vous avez souscrits.&lt;br \/&gt;Vous pouvez vous d\u00e9sinscrire du marketing direct \u00e0 tout moment en suivant les instructions fournies dans chaque communication marketing.&lt;br \/&gt; &lt;br \/&gt;Droit d\u2019introduire une r\u00e9clamation aupr\u00e8s d\u2019une autorit\u00e9 de surveillance : &lt;br \/&gt;Si vous estimez que BALI SPIRIT traite vos donn\u00e9es de mani\u00e8re incorrecte, vous pouvez nous contacter. Vous avez \u00e9galement le droit de d\u00e9poser une plainte aupr\u00e8s de l&#8217;autorit\u00e9 comp\u00e9tente en mati\u00e8re de protection des donn\u00e9es (aepd.es). &lt;br \/&gt; &lt;br \/&gt;Droit \u00e0 la limitation du traitement :&lt;br \/&gt;Vous avez le droit de demander \u00e0 BALI SPIRIT de limiter le traitement de vos donn\u00e9es personnelles dans les circonstances suivantes :&lt;br \/&gt;* Si vous vous opposez au traitement de vos donn\u00e9es fond\u00e9 sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT, BALI SPIRIT devra limiter tout traitement de ces donn\u00e9es en attendant la v\u00e9rification de cet int\u00e9r\u00eat l\u00e9gitime.&lt;br \/&gt;* Si vous affirmez que vos donn\u00e9es personnelles sont incorrectes, BALI SPIRIT doit limiter tout traitement de ces donn\u00e9es jusqu&#8217;\u00e0 ce que leur exactitude soit v\u00e9rifi\u00e9e.&lt;br \/&gt;* Si le traitement est illicite, vous pouvez vous opposer \u00e0 la suppression de vos donn\u00e9es personnelles et demander \u00e0 la place la limitation de leur utilisation.&lt;br \/&gt;* si BALI SPIRIT n&#8217;a plus besoin des donn\u00e9es personnelles, mais que vous en avez besoin pour la constatation, l&#8217;exercice ou la d\u00e9fense de droits en justice.&lt;br \/&gt; &lt;br \/&gt;Exercice des droits :&lt;br \/&gt;Nous prenons la protection des donn\u00e9es tr\u00e8s au s\u00e9rieux et disposons donc d&#8217;une \u00e9quipe d\u00e9di\u00e9e au service client pour traiter vos demandes concernant les droits mentionn\u00e9s ci-dessus. Pour exercer ces droits, veuillez envoyer votre demande \u00e0 recepcion@gmail.com en joignant une copie de votre carte d&#8217;identit\u00e9 ou autre pi\u00e8ce d&#8217;identit\u00e9. &lt;br \/&gt; &lt;br \/&gt;Mises \u00e0 jour de notre politique de confidentialit\u00e9 :&lt;br \/&gt;Nous pourrions \u00eatre amen\u00e9s \u00e0 mettre \u00e0 jour notre Politique de confidentialit\u00e9. La version la plus r\u00e9cente est toujours disponible sur notre site web. Nous vous informerons de toute modification importante apport\u00e9e \u00e0 la Politique de confidentialit\u00e9, notamment concernant la finalit\u00e9 du traitement de vos donn\u00e9es personnelles, l&#8217;identit\u00e9 du responsable du traitement ou vos droits.  &lt;br \/&gt; &lt;br \/&gt;ACHATS EN LIGNE&lt;br \/&gt; &lt;br \/&gt;Pourquoi utilisons-nous vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour g\u00e9rer vos r\u00e9servations et achats en ligne chez BALI SPIRIT en traitant vos achats, r\u00e9servations, changements de dates, annulations et remboursements via nos services en ligne, et pour vous envoyer des notifications concernant le statut de votre r\u00e9servation, la livraison de votre bon cadeau ou, en cas de probl\u00e8me, l&#8217;exp\u00e9dition des articles, conform\u00e9ment aux conditions g\u00e9n\u00e9rales de vente.&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour g\u00e9rer vos paiements.&lt;br \/&gt;Nous utiliserons \u00e9galement vos donn\u00e9es pour traiter toute r\u00e9clamation ou tout probl\u00e8me concernant le service re\u00e7u.&lt;br \/&gt;Vos donn\u00e9es personnelles seront utilis\u00e9es pour vous identifier.&lt;br \/&gt; &lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons les cat\u00e9gories de donn\u00e9es personnelles suivantes :&lt;br \/&gt;* Coordonn\u00e9es de contact telles que : nom, pr\u00e9nom, adresse e-mail et num\u00e9ro de t\u00e9l\u00e9phone&lt;br \/&gt;* Informations et historique des paiements pour les r\u00e9servations et les achats de coffrets cadeaux&lt;br \/&gt;* Informations sur la commande&lt;br \/&gt; &lt;br \/&gt;Qui a acc\u00e8s \u00e0 vos donn\u00e9es personnelles ?&lt;br \/&gt;Les donn\u00e9es transmises \u00e0 des tiers, utilis\u00e9es uniquement pour vous proposer les services mentionn\u00e9s ci-dessus, incluront les soci\u00e9t\u00e9s qui valideront votre adresse, les soci\u00e9t\u00e9s de communication qui vous enverront la confirmation de votre commande, ainsi que les entrep\u00f4ts des transporteurs et les fournisseurs en lien avec la livraison de la commande.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;BALI SPIRIT traite vos donn\u00e9es personnelles afin de fournir le service que vous avez r\u00e9serv\u00e9. Ce traitement est \u00e9galement n\u00e9cessaire pour la livraison du coffret cadeau \u00e0 vous-m\u00eame ou \u00e0 son destinataire si vous avez opt\u00e9 pour la livraison \u00e0 domicile. &lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Nous conserverons vos donn\u00e9es pendant toute la dur\u00e9e de notre relation commerciale et par la suite jusqu&#8217;\u00e0 ce que vous nous demandiez le contraire.&lt;br \/&gt; &lt;br \/&gt; MARKETING DIRECT&lt;br \/&gt;\u00c0 quoi servent vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour vous envoyer des offres marketing, des enqu\u00eates d&#8217;information et des invitations par courriel, SMS, t\u00e9l\u00e9phone et courrier postal.&lt;br \/&gt;Pour optimiser votre exp\u00e9rience avec BALI SPIRIT, nous vous fournirons des informations pertinentes, vous recommanderons des produits et vous enverrons des rappels concernant vos r\u00e9servations en cours, vos achats de coffrets cadeaux, les cadeaux que vous avez re\u00e7us et les offres personnalis\u00e9es. Ces services seront bas\u00e9s sur vos achats et r\u00e9servations pr\u00e9c\u00e9dents, vos choix et les informations que vous nous avez communiqu\u00e9es. &lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons les cat\u00e9gories de donn\u00e9es personnelles suivantes :&lt;br \/&gt;* informaci\u00f3n de contacto como: direcci\u00f3n de correo electr\u00f3nico, n\u00famero de tel\u00e9fono y email&lt;br \/&gt;* Les produits et offres que vous avez s\u00e9lectionn\u00e9s&lt;br \/&gt;*Si vous avez confirm\u00e9 que vous souhaitez que nous vous tenions inform\u00e9(e) des actualit\u00e9s et des promotions de BALI SPIRIT.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le traitement de vos donn\u00e9es personnelles est fond\u00e9 sur votre consentement lorsque vous acceptez le marketing direct.&lt;br \/&gt;Droit de retirer votre consentement :&lt;br \/&gt;Vous avez le droit de retirer votre consentement au traitement de vos donn\u00e9es personnelles \u00e0 tout moment, et vous pouvez \u00e9galement vous opposer au marketing direct.&lt;br \/&gt;Ce faisant, BALI SPIRIT ne pourra pas vous envoyer d&#8217;offres ni d&#8217;informations marketing directes sur la base de votre consentement.&lt;br \/&gt;Vous pouvez retirer votre consentement au marketing direct en suivant les instructions fournies dans chaque communication commerciale, ou en envoyant une demande \u00e0 l&#8217;adresse \u00e9lectronique recepcion@balispirit.es en joignant une copie de votre carte d&#8217;identit\u00e9 ou de votre pi\u00e8ce d&#8217;identit\u00e9.&lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Nous conserverons vos donn\u00e9es \u00e0 des fins de marketing direct jusqu&#8217;\u00e0 ce que vous retiriez votre consentement.&lt;br \/&gt; &lt;br \/&gt;SERVICE CLIENT&lt;br \/&gt;\u00c0 quoi servent vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour g\u00e9rer toute demande, traiter les r\u00e9clamations ou les probl\u00e8mes concernant les r\u00e9servations pass\u00e9es ou en cours, les achats de coffrets cadeaux ou leur livraison, par t\u00e9l\u00e9phone ou via les r\u00e9seaux sociaux.&lt;br \/&gt;Nous pouvons \u00e9galement vous contacter en cas de probl\u00e8me avec votre commande.&lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons toutes les donn\u00e9es que vous nous fournirez, y compris les cat\u00e9gories suivantes :&lt;br \/&gt;* Coordonn\u00e9es de contact telles que : adresse, courriel et num\u00e9ro de t\u00e9l\u00e9phone&lt;br \/&gt;* Informations sur les commandes ou les r\u00e9servations&lt;br \/&gt;* Correspondance sur tout sujet&lt;br \/&gt;Qui a acc\u00e8s \u00e0 vos donn\u00e9es personnelles ?&lt;br \/&gt;Les donn\u00e9es transmises \u00e0 des tiers seront utilis\u00e9es uniquement pour vous fournir les services mentionn\u00e9s.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le traitement de vos donn\u00e9es personnelles est fond\u00e9 sur l\u2019int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT ou de l\u2019une de ses soci\u00e9t\u00e9s du groupe.&lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Dans les d\u00e9lais l\u00e9gaux \u00e9tablis.&lt;br \/&gt;Droit de s\u2019opposer au traitement des donn\u00e9es fond\u00e9 sur l\u2019int\u00e9r\u00eat l\u00e9gitime :&lt;br \/&gt;Vous avez le droit de vous opposer au traitement de vos donn\u00e9es personnelles fond\u00e9 sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT. BALI SPIRIT cessera de traiter vos donn\u00e9es personnelles \u00e0 moins de pouvoir d\u00e9montrer un motif l\u00e9gitime et imp\u00e9rieux justifiant ce traitement et pr\u00e9valant sur vos int\u00e9r\u00eats et vos droits, ou en cas de proc\u00e9dure judiciaire. &lt;br \/&gt; &lt;br \/&gt;COMP\u00c9TITIONS&lt;br \/&gt;\u00c0 quoi servent vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous traiterons vos donn\u00e9es personnelles lorsque vous participerez \u00e0 nos concours, dont le r\u00e8glement vous sera communiqu\u00e9 ult\u00e9rieurement. BALI SPIRIT utilisera vos donn\u00e9es personnelles pour contacter les participants concernant le concours, avant et apr\u00e8s l&#8217;\u00e9v\u00e9nement, pour identifier les participants, v\u00e9rifier leur \u00e2ge, contacter les gagnants et pour la remise et le suivi des prix. &lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons les cat\u00e9gories de donn\u00e9es personnelles suivantes :&lt;br \/&gt;* Informations de contact telles que : nom, adresse, adresse e-mail et num\u00e9ro de t\u00e9l\u00e9phone&lt;br \/&gt;* \u00e2ge&lt;br \/&gt;* Informations fournies dans le cadre du concours&lt;br \/&gt;* images.&lt;br \/&gt;Qui a acc\u00e8s \u00e0 vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous transmettons vos donn\u00e9es aux soci\u00e9t\u00e9s charg\u00e9es de l&#8217;envoi des prix, qui les utilisent uniquement pour vous proposer les services mentionn\u00e9s ci-dessus.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le traitement de vos donn\u00e9es personnelles est fond\u00e9 sur votre consentement lorsque vous d\u00e9cidez de participer \u00e0 un concours.&lt;br \/&gt;Droit de retirer votre consentement :&lt;br \/&gt;Vous avez le droit de retirer votre consentement au traitement de vos donn\u00e9es personnelles \u00e0 tout moment. Dans ce cas, BALI SPIRIT ne sera plus en mesure de vous proposer les services susmentionn\u00e9s. &lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Dans les d\u00e9lais l\u00e9gaux et tant que vous ne r\u00e9voquez pas votre consentement.&lt;br \/&gt; &lt;\/p&gt;&lt;\/div&gt;&lt;footer class=&#8221;entry-footer default-max-width&#8221;&gt;&lt;span class=&#8221;edit-link&#8221;&gt;&lt;a class=&#8221;post-edit-link&#8221; href=&#8221;https:\/\/balispirit.es\/wp-admin\/post.php?post=321&amp;action=edit&#8221;&gt;Editar&lt;span class=&#8221;screen-reader-text&#8221;&gt;Pol\u00edtica de Privacidad&lt;\/span&gt;&lt;\/a&gt;&lt;\/span&gt;&lt;\/footer&gt;&lt;\/article&gt;&lt;\/div&gt;&lt;\/div&gt;&lt;\/div&gt;&lt;\/section&gt;&lt;\/div&gt;&lt;p&gt;4.- &lt;\/p&gt;&lt;p&gt;Le respect de la vie priv\u00e9e est primordial pour BALI SPIRIT, S.L. et nous souhaitons maintenir une attitude ouverte et transparente dans le traitement de vos donn\u00e9es personnelles..&lt;\/p&gt;&lt;&gt;&lt;&gt;&lt;\/p&gt;&lt;p&gt;BALI SPIRIT, S.L. est responsable du traitement des donn\u00e9es personnelles que vous nous fournissez et est responsable de ces donn\u00e9es personnelles conform\u00e9ment \u00e0 la r\u00e9glementation applicable en mati\u00e8re de protection des donn\u00e9es.&lt;br \/&gt;Nom de l&#8217;entreprise:BALI SPIRIT, S.L.&lt;br \/&gt;Num\u00e9ro d&#8217;identification fiscale : CIF B-65118481&lt;br \/&gt;Si\u00e8ge social : RueAribau, 59 08011 Barcelona&lt;br \/&gt;Num\u00e9ro de t\u00e9l\u00e9phone de contact : 934 517 085&lt;br \/&gt;Adresse \u00e9lectronique de contact :info@balispirit.es&lt;br \/&gt;  &lt;br \/&gt;O\u00f9 stockons-nous vos donn\u00e9es ?&lt;br \/&gt;Les donn\u00e9es que nous recueillons vous concernant sont stock\u00e9es au sein de l\u2019Espace \u00e9conomique europ\u00e9en (\u00ab EEE \u00bb), mais peuvent \u00e9galement \u00eatre transf\u00e9r\u00e9es et trait\u00e9es dans un pays situ\u00e9 en dehors de l\u2019EEE. Tout transfert de vos donn\u00e9es personnelles sera effectu\u00e9 conform\u00e9ment \u00e0 la l\u00e9gislation applicable. Pour les transferts hors de l\u2019EEE, GRUPO AIRE utilisera les clauses contractuelles types de protection des donn\u00e9es adopt\u00e9es par la Commission europ\u00e9enne et le Bouclier de protection des donn\u00e9es UE-\u00c9tats-Unis comme garantie pour les transferts vers des pays ne b\u00e9n\u00e9ficiant pas d\u2019une d\u00e9cision d\u2019ad\u00e9quation de la Commission europ\u00e9enne.   &lt;br \/&gt; &lt;br \/&gt;Avec qui partageons-nous vos donn\u00e9es ?&lt;br \/&gt;Vos donn\u00e9es personnelles ne seront jamais partag\u00e9es, vendues ni \u00e9chang\u00e9es avec des tiers ext\u00e9rieurs \u00e0 BALI SPIRIT, S.L. Les donn\u00e9es transmises \u00e0 des tiers seront utilis\u00e9es uniquement pour vous fournir nos services. Nous d\u00e9taillerons les cat\u00e9gories de tiers ayant acc\u00e8s \u00e0 vos donn\u00e9es pour chaque traitement sp\u00e9cifique. &lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le fondement juridique du traitement est l\u2019ex\u00e9cution du service que vous avez contract\u00e9 ainsi que le consentement que vous avez donn\u00e9 pour des finalit\u00e9s autres que ces services.&lt;br \/&gt; &lt;br \/&gt;Quels sont vos droits ?&lt;br \/&gt;Droit d&#8217;acc\u00e8s : &lt;br \/&gt;Toute personne a le droit d&#8217;obtenir la confirmation que BALI SPIRIT traite ou non des donn\u00e9es personnelles la concernant.&lt;br \/&gt; &lt;br \/&gt;Droit \u00e0 la portabilit\u00e9 :&lt;br \/&gt;Lorsque BALI SPIRIT traite vos donn\u00e9es personnelles par des moyens automatis\u00e9s, sur la base de votre consentement ou d&#8217;un contrat, vous avez le droit d&#8217;obtenir une copie de vos donn\u00e9es dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine, qui vous sera transf\u00e9r\u00e9e ou transf\u00e9r\u00e9e \u00e0 un tiers. Cette copie ne comprendra que les donn\u00e9es personnelles que vous nous avez fournies. &lt;br \/&gt; &lt;br \/&gt;Droit de rectification : &lt;br \/&gt;Vous avez le droit de demander la rectification de vos donn\u00e9es personnelles si elles sont inexactes, y compris le droit de compl\u00e9ter les donn\u00e9es qui apparaissent incompl\u00e8tes. &lt;br \/&gt; &lt;br \/&gt;Droit \u00e0 l&#8217;effacement :&lt;br \/&gt;Vous avez le droit d&#8217;obtenir \u00e0 tout moment, sans d\u00e9lai indu, l&#8217;effacement de toutes les donn\u00e9es personnelles vous concernant trait\u00e9es par BALI SPIRIT, sauf dans les situations suivantes :&lt;br \/&gt;* a un probl\u00e8me persistant avec le service client&lt;br \/&gt;* Vous avez une commande ou une r\u00e9servation en cours qui n&#8217;a pas encore \u00e9t\u00e9 honor\u00e9e, ou une commande de coffret cadeau \u00e0 livrer \u00e0 domicile qui a \u00e9t\u00e9 exp\u00e9di\u00e9e ou dont l&#8217;exp\u00e9dition n&#8217;a pas \u00e9t\u00e9 termin\u00e9e.&lt;br \/&gt;* Il est soup\u00e7onn\u00e9 ou confirm\u00e9 que vous avez fait un usage abusif de nos services au cours des quatre derni\u00e8res ann\u00e9es.&lt;br \/&gt;* Vous avez effectu\u00e9 un achat, nous conserverons donc vos donn\u00e9es personnelles relatives \u00e0 la transaction \u00e0 des fins comptables.&lt;br \/&gt;* l&#8217;existence d&#8217;une obligation l\u00e9gale de conserver vos donn\u00e9es.&lt;br \/&gt; &lt;br \/&gt;Droit de s\u2019opposer au traitement des donn\u00e9es fond\u00e9 sur l\u2019int\u00e9r\u00eat l\u00e9gitime :&lt;br \/&gt;Vous avez le droit de vous opposer au traitement de vos donn\u00e9es personnelles fond\u00e9 sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT. BALI SPIRIT cessera de traiter vos donn\u00e9es personnelles \u00e0 moins de pouvoir d\u00e9montrer l&#8217;existence de motifs l\u00e9gitimes et imp\u00e9rieux justifiant ce traitement et pr\u00e9valant sur vos int\u00e9r\u00eats, droits et libert\u00e9s, ou pour la constatation, l&#8217;exercice ou la d\u00e9fense de droits en justice. &lt;br \/&gt; &lt;br \/&gt;Droit de s&#8217;opposer au marketing direct :&lt;br \/&gt;Vous avez le droit de vous opposer au marketing direct, y compris au profilage effectu\u00e9 \u00e0 des fins de marketing direct en lien avec les services que vous avez souscrits.&lt;br \/&gt;Vous pouvez vous d\u00e9sinscrire du marketing direct \u00e0 tout moment en suivant les instructions fournies dans chaque communication marketing.&lt;br \/&gt; &lt;br \/&gt;Droit d\u2019introduire une r\u00e9clamation aupr\u00e8s d\u2019une autorit\u00e9 de surveillance : &lt;br \/&gt;Si vous estimez que BALI SPIRIT traite vos donn\u00e9es de mani\u00e8re incorrecte, vous pouvez nous contacter. Vous avez \u00e9galement le droit de d\u00e9poser une plainte aupr\u00e8s de l&#8217;autorit\u00e9 comp\u00e9tente en mati\u00e8re de protection des donn\u00e9es (aepd.es). &lt;br \/&gt; &lt;br \/&gt;Droit \u00e0 la limitation du traitement :&lt;br \/&gt;Vous avez le droit de demander \u00e0 BALI SPIRIT de limiter le traitement de vos donn\u00e9es personnelles dans les circonstances suivantes :&lt;br \/&gt;* Si vous vous opposez au traitement de vos donn\u00e9es fond\u00e9 sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT, BALI SPIRIT devra limiter tout traitement de ces donn\u00e9es en attendant la v\u00e9rification de cet int\u00e9r\u00eat l\u00e9gitime.&lt;br \/&gt;* Si vous affirmez que vos donn\u00e9es personnelles sont incorrectes, BALI SPIRIT doit limiter tout traitement de ces donn\u00e9es jusqu&#8217;\u00e0 ce que leur exactitude soit v\u00e9rifi\u00e9e.&lt;br \/&gt;* Si le traitement est illicite, vous pouvez vous opposer \u00e0 la suppression de vos donn\u00e9es personnelles et demander \u00e0 la place la limitation de leur utilisation.&lt;br \/&gt;* si BALI SPIRIT n&#8217;a plus besoin des donn\u00e9es personnelles, mais que vous en avez besoin pour la constatation, l&#8217;exercice ou la d\u00e9fense de droits en justice.&lt;br \/&gt; &lt;br \/&gt;Exercice des droits :&lt;br \/&gt;Nous prenons la protection des donn\u00e9es tr\u00e8s au s\u00e9rieux et disposons donc d&#8217;une \u00e9quipe d\u00e9di\u00e9e au service client pour traiter vos demandes concernant les droits mentionn\u00e9s ci-dessus. Pour exercer ces droits, veuillez envoyer votre demande \u00e0 recepcion@gmail.com en joignant une copie de votre carte d&#8217;identit\u00e9 ou autre pi\u00e8ce d&#8217;identit\u00e9. &lt;br \/&gt; &lt;br \/&gt;Mises \u00e0 jour de notre politique de confidentialit\u00e9 :&lt;br \/&gt;Nous pourrions \u00eatre amen\u00e9s \u00e0 mettre \u00e0 jour notre Politique de confidentialit\u00e9. La version la plus r\u00e9cente est toujours disponible sur notre site web. Nous vous informerons de toute modification importante apport\u00e9e \u00e0 la Politique de confidentialit\u00e9, notamment concernant la finalit\u00e9 du traitement de vos donn\u00e9es personnelles, l&#8217;identit\u00e9 du responsable du traitement ou vos droits.  &lt;br \/&gt; &lt;br \/&gt;ACHATS EN LIGNE&lt;br \/&gt; &lt;br \/&gt;Pourquoi utilisons-nous vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour g\u00e9rer vos r\u00e9servations et achats en ligne chez BALI SPIRIT en traitant vos achats, r\u00e9servations, changements de dates, annulations et remboursements via nos services en ligne, et pour vous envoyer des notifications concernant le statut de votre r\u00e9servation, la livraison de votre bon cadeau ou, en cas de probl\u00e8me, l&#8217;exp\u00e9dition des articles, conform\u00e9ment aux conditions g\u00e9n\u00e9rales de vente.&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour g\u00e9rer vos paiements.&lt;br \/&gt;Nous utiliserons \u00e9galement vos donn\u00e9es pour traiter toute r\u00e9clamation ou tout probl\u00e8me concernant le service re\u00e7u.&lt;br \/&gt;Vos donn\u00e9es personnelles seront utilis\u00e9es pour vous identifier.&lt;br \/&gt; &lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons les cat\u00e9gories de donn\u00e9es personnelles suivantes :&lt;br \/&gt;* Coordonn\u00e9es de contact telles que : nom, pr\u00e9nom, adresse e-mail et num\u00e9ro de t\u00e9l\u00e9phone&lt;br \/&gt;* Informations et historique des paiements pour les r\u00e9servations et les achats de coffrets cadeaux&lt;br \/&gt;* Informations sur la commande&lt;br \/&gt; &lt;br \/&gt;Qui a acc\u00e8s \u00e0 vos donn\u00e9es personnelles ?&lt;br \/&gt;Les donn\u00e9es transmises \u00e0 des tiers, utilis\u00e9es uniquement pour vous proposer les services mentionn\u00e9s ci-dessus, incluront les soci\u00e9t\u00e9s qui valideront votre adresse, les soci\u00e9t\u00e9s de communication qui vous enverront la confirmation de votre commande, ainsi que les entrep\u00f4ts des transporteurs et les fournisseurs en lien avec la livraison de la commande.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;BALI SPIRIT traite vos donn\u00e9es personnelles afin de fournir le service que vous avez r\u00e9serv\u00e9. Ce traitement est \u00e9galement n\u00e9cessaire pour la livraison du coffret cadeau \u00e0 vous-m\u00eame ou \u00e0 son destinataire si vous avez opt\u00e9 pour la livraison \u00e0 domicile. &lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Nous conserverons vos donn\u00e9es pendant toute la dur\u00e9e de notre relation commerciale et par la suite jusqu&#8217;\u00e0 ce que vous nous demandiez le contraire.&lt;br \/&gt; &lt;br \/&gt; MARKETING DIRECT&lt;br \/&gt;\u00c0 quoi servent vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour vous envoyer des offres marketing, des enqu\u00eates d&#8217;information et des invitations par courriel, SMS, t\u00e9l\u00e9phone et courrier postal.&lt;br \/&gt;Pour optimiser votre exp\u00e9rience avec BALI SPIRIT, nous vous fournirons des informations pertinentes, vous recommanderons des produits et vous enverrons des rappels concernant vos r\u00e9servations en cours, vos achats de coffrets cadeaux, les cadeaux que vous avez re\u00e7us et les offres personnalis\u00e9es. Ces services seront bas\u00e9s sur vos achats et r\u00e9servations pr\u00e9c\u00e9dents, vos choix et les informations que vous nous avez communiqu\u00e9es. &lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons les cat\u00e9gories de donn\u00e9es personnelles suivantes :&lt;br \/&gt;* informaci\u00f3n de contacto como: direcci\u00f3n de correo electr\u00f3nico, n\u00famero de tel\u00e9fono y email&lt;br \/&gt;* Les produits et offres que vous avez s\u00e9lectionn\u00e9s&lt;br \/&gt;*Si vous avez confirm\u00e9 que vous souhaitez que nous vous tenions inform\u00e9(e) des actualit\u00e9s et des promotions de BALI SPIRIT.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le traitement de vos donn\u00e9es personnelles est fond\u00e9 sur votre consentement lorsque vous acceptez le marketing direct.&lt;br \/&gt;Droit de retirer votre consentement :&lt;br \/&gt;Vous avez le droit de retirer votre consentement au traitement de vos donn\u00e9es personnelles \u00e0 tout moment, et vous pouvez \u00e9galement vous opposer au marketing direct.&lt;br \/&gt;Ce faisant, BALI SPIRIT ne pourra pas vous envoyer d&#8217;offres ni d&#8217;informations marketing directes sur la base de votre consentement.&lt;br \/&gt;Vous pouvez retirer votre consentement au marketing direct en suivant les instructions fournies dans chaque communication commerciale, ou en envoyant une demande \u00e0 l&#8217;adresse \u00e9lectronique recepcion@balispirit.es en joignant une copie de votre carte d&#8217;identit\u00e9 ou de votre pi\u00e8ce d&#8217;identit\u00e9.&lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Nous conserverons vos donn\u00e9es \u00e0 des fins de marketing direct jusqu&#8217;\u00e0 ce que vous retiriez votre consentement.&lt;br \/&gt; &lt;br \/&gt;SERVICE CLIENT&lt;br \/&gt;\u00c0 quoi servent vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous utiliserons vos donn\u00e9es personnelles pour g\u00e9rer toute demande, traiter les r\u00e9clamations ou les probl\u00e8mes concernant les r\u00e9servations pass\u00e9es ou en cours, les achats de coffrets cadeaux ou leur livraison, par t\u00e9l\u00e9phone ou via les r\u00e9seaux sociaux.&lt;br \/&gt;Nous pouvons \u00e9galement vous contacter en cas de probl\u00e8me avec votre commande.&lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons toutes les donn\u00e9es que vous nous fournirez, y compris les cat\u00e9gories suivantes :&lt;br \/&gt;* Coordonn\u00e9es de contact telles que : adresse, courriel et num\u00e9ro de t\u00e9l\u00e9phone&lt;br \/&gt;* Informations sur les commandes ou les r\u00e9servations&lt;br \/&gt;* Correspondance sur tout sujet&lt;br \/&gt;Qui a acc\u00e8s \u00e0 vos donn\u00e9es personnelles ?&lt;br \/&gt;Les donn\u00e9es transmises \u00e0 des tiers seront utilis\u00e9es uniquement pour vous fournir les services mentionn\u00e9s.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le traitement de vos donn\u00e9es personnelles est fond\u00e9 sur l\u2019int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT ou de l\u2019une de ses soci\u00e9t\u00e9s du groupe.&lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Dans les d\u00e9lais l\u00e9gaux \u00e9tablis.&lt;br \/&gt;Droit de s\u2019opposer au traitement des donn\u00e9es fond\u00e9 sur l\u2019int\u00e9r\u00eat l\u00e9gitime :&lt;br \/&gt;Vous avez le droit de vous opposer au traitement de vos donn\u00e9es personnelles fond\u00e9 sur l&#8217;int\u00e9r\u00eat l\u00e9gitime de BALI SPIRIT. BALI SPIRIT cessera de traiter vos donn\u00e9es personnelles \u00e0 moins de pouvoir d\u00e9montrer un motif l\u00e9gitime et imp\u00e9rieux justifiant ce traitement et pr\u00e9valant sur vos int\u00e9r\u00eats et vos droits, ou en cas de proc\u00e9dure judiciaire. &lt;br \/&gt; &lt;br \/&gt;COMP\u00c9TITIONS&lt;br \/&gt;\u00c0 quoi servent vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous traiterons vos donn\u00e9es personnelles lorsque vous participerez \u00e0 nos concours, dont le r\u00e8glement vous sera communiqu\u00e9 ult\u00e9rieurement. BALI SPIRIT utilisera vos donn\u00e9es personnelles pour contacter les participants concernant le concours, avant et apr\u00e8s l&#8217;\u00e9v\u00e9nement, pour identifier les participants, v\u00e9rifier leur \u00e2ge, contacter les gagnants et pour la remise et le suivi des prix. &lt;br \/&gt; &lt;br \/&gt;Quel type de donn\u00e9es personnelles traitons-nous ?&lt;br \/&gt;Nous traiterons les cat\u00e9gories de donn\u00e9es personnelles suivantes :&lt;br \/&gt;* Informations de contact telles que : nom, adresse, adresse e-mail et num\u00e9ro de t\u00e9l\u00e9phone&lt;br \/&gt;* \u00e2ge&lt;br \/&gt;* Informations fournies dans le cadre du concours&lt;br \/&gt;* images.&lt;br \/&gt;Qui a acc\u00e8s \u00e0 vos donn\u00e9es personnelles ?&lt;br \/&gt;Nous transmettons vos donn\u00e9es aux soci\u00e9t\u00e9s charg\u00e9es de l&#8217;envoi des prix, qui les utilisent uniquement pour vous proposer les services mentionn\u00e9s ci-dessus.&lt;br \/&gt; &lt;br \/&gt;Quel est le fondement juridique du traitement de vos donn\u00e9es personnelles ?&lt;br \/&gt;Le traitement de vos donn\u00e9es personnelles est fond\u00e9 sur votre consentement lorsque vous d\u00e9cidez de participer \u00e0 un concours.&lt;br \/&gt;Droit de retirer votre consentement :&lt;br \/&gt;Vous avez le droit de retirer votre consentement au traitement de vos donn\u00e9es personnelles \u00e0 tout moment. Dans ce cas, BALI SPIRIT ne sera plus en mesure de vous proposer les services susmentionn\u00e9s. &lt;br \/&gt; &lt;br \/&gt;Combien de temps conservons-nous vos donn\u00e9es ?&lt;br \/&gt;Dans les d\u00e9lais l\u00e9gaux et tant que vous ne r\u00e9voquez pas votre consentement.&lt;\/p&gt;\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&lt;div id=&#8221;content&#8221;&gt;&lt;section&gt;&lt;div&gt;&lt;div&gt;&lt;div&gt;&lt;article id=&#8221;post-321&#8243;&gt;&lt;div&gt;&lt;p&gt;4.- &lt;\/p&gt;&lt;p&gt;Le respect de la vie priv\u00e9e est primordial pour BALI SPIRIT, S.L. et nous souhaitons maintenir une attitude ouverte et transparente dans le traitement de vos donn\u00e9es personnelles..&lt;\/p&gt;&lt;&gt;&lt;&gt;&lt;\/p&gt;&lt;p&gt;BALI SPIRIT, S.L. est responsable du traitement des donn\u00e9es personnelles que vous nous fournissez et est responsable de ces donn\u00e9es personnelles conform\u00e9ment \u00e0 la r\u00e9glementation [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-21577","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>politique de confidentialit\u00e9 - Bali Spirit<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"politique de confidentialit\u00e9 - Bali Spirit\" \/>\n<meta property=\"og:description\" content=\"&lt;div id=&#8221;content&#8221;&gt;&lt;section&gt;&lt;div&gt;&lt;div&gt;&lt;div&gt;&lt;article id=&#8221;post-321&#8243;&gt;&lt;div&gt;&lt;p&gt;4.- &lt;\/p&gt;&lt;p&gt;Le respect de la vie priv\u00e9e est primordial pour BALI SPIRIT, S.L. et nous souhaitons maintenir une attitude ouverte et transparente dans le traitement de vos donn\u00e9es personnelles..&lt;\/p&gt;&lt;&gt;&lt;&gt;&lt;\/p&gt;&lt;p&gt;BALI SPIRIT, S.L. est responsable du traitement des donn\u00e9es personnelles que vous nous fournissez et est responsable de ces donn\u00e9es personnelles conform\u00e9ment \u00e0 la r\u00e9glementation [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Bali Spirit\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T08:50:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/balispirit.es\/wp-content\/uploads\/2023\/02\/banner-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/politique-de-confidentialite\\\/\",\"name\":\"politique de confidentialit\u00e9 - Bali Spirit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/#website\"},\"datePublished\":\"2023-02-26T23:12:29+00:00\",\"dateModified\":\"2026-03-30T08:50:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/balispirit.es\\\/fr\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/\",\"name\":\"Bali Spirit\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/balispirit.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"politique de confidentialit\u00e9 - Bali Spirit","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"politique de confidentialit\u00e9 - Bali Spirit","og_description":"&lt;div id=&#8221;content&#8221;&gt;&lt;section&gt;&lt;div&gt;&lt;div&gt;&lt;div&gt;&lt;article id=&#8221;post-321&#8243;&gt;&lt;div&gt;&lt;p&gt;4.- &lt;\/p&gt;&lt;p&gt;Le respect de la vie priv\u00e9e est primordial pour BALI SPIRIT, S.L. et nous souhaitons maintenir une attitude ouverte et transparente dans le traitement de vos donn\u00e9es personnelles..&lt;\/p&gt;&lt;&gt;&lt;&gt;&lt;\/p&gt;&lt;p&gt;BALI SPIRIT, S.L. est responsable du traitement des donn\u00e9es personnelles que vous nous fournissez et est responsable de ces donn\u00e9es personnelles conform\u00e9ment \u00e0 la r\u00e9glementation [&hellip;]","og_url":"https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/","og_site_name":"Bali Spirit","article_modified_time":"2026-03-30T08:50:46+00:00","og_image":[{"width":709,"height":251,"url":"https:\/\/balispirit.es\/wp-content\/uploads\/2023\/02\/banner-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/","url":"https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/","name":"politique de confidentialit\u00e9 - Bali Spirit","isPartOf":{"@id":"https:\/\/balispirit.es\/fr\/#website"},"datePublished":"2023-02-26T23:12:29+00:00","dateModified":"2026-03-30T08:50:46+00:00","breadcrumb":{"@id":"https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/balispirit.es\/fr\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/balispirit.es\/fr\/"},{"@type":"ListItem","position":2,"name":"politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/balispirit.es\/fr\/#website","url":"https:\/\/balispirit.es\/fr\/","name":"Bali Spirit","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/balispirit.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/pages\/21577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/comments?post=21577"}],"version-history":[{"count":2,"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/pages\/21577\/revisions"}],"predecessor-version":[{"id":22083,"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/pages\/21577\/revisions\/22083"}],"wp:attachment":[{"href":"https:\/\/balispirit.es\/fr\/wp-json\/wp\/v2\/media?parent=21577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}